{"id":33687,"date":"2021-06-23T16:22:17","date_gmt":"2021-06-23T21:22:17","guid":{"rendered":"https:\/\/www.emanualonline.com\/blog\/?p=33687"},"modified":"2021-06-23T22:14:25","modified_gmt":"2021-06-24T03:14:25","slug":"rivian-r1ts-highly-functional-interior-includes-a-removable-speaker","status":"publish","type":"post","link":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker","title":{"rendered":"Rivian R1T&#8217;s Highly-Functional Interior Includes a Removable Speaker"},"content":{"rendered":"<p class=\"custom-first\">Rivian gives more insight into its highly anticipated R1T pickup truck.<\/p>\n<p>Back in April, Rivian released detailed specifications on the performance and capacity of its futuristic pickup truck, the all-electric R1T. The 135 kWh model features a dual-motor setup granting 754 hp of all-wheel-drive power, good enough to hit 0-60mph in just 3 seconds. It comes with 250-400 miles of all-electric range and should be pretty good at its job, thanks to the 1760 lbs payload capacity and 11,000 lbs towing capacity. And until now, this was pretty much everything we knew about the R1T.<\/p>\n<p>Now that the delivery date is closing in, Rivian has finally uncovered further details on what&#8217;s inside the truck. On that note, saying the R1T gets a posh interior would be an understatement as it boasts premium leather covering on seats and steering wheel, quick-drying Chilewich floor mats, and a microfiber headliner. And that&#8217;s just the tip of the iceberg when it comes to creature comfort.<\/p>\n<div id='gallery-1' class='gallery galleryid-33687 gallery-columns-4 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13.jpg'><img decoding=\"async\" width=\"1200\" height=\"1552\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13.jpg\" class=\"attachment-full size-full lazyload\" alt=\"2022 Rivian R1T\" data-srcset=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13.jpg 1200w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13-232x300.jpg 232w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13-792x1024.jpg 792w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13-768x993.jpg 768w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13-1188x1536.jpg 1188w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1552;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01.jpg'><img decoding=\"async\" width=\"1200\" height=\"1552\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" data-srcset=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01.jpg 1200w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01-232x300.jpg 232w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01-792x1024.jpg 792w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01-768x993.jpg 768w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01-1188x1536.jpg 1188w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1552;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08.jpg'><img decoding=\"async\" width=\"1200\" height=\"1552\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08.jpg\" class=\"attachment-full size-full lazyload\" alt=\"2022 Rivian R1T\" data-srcset=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08.jpg 1200w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08-232x300.jpg 232w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08-792x1024.jpg 792w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08-768x993.jpg 768w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08-1188x1536.jpg 1188w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1552;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10.jpg'><img decoding=\"async\" width=\"1200\" height=\"1552\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10.jpg\" class=\"attachment-full size-full lazyload\" alt=\"2022 Rivian R1T\" data-srcset=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10.jpg 1200w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10-232x300.jpg 232w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10-792x1024.jpg 792w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10-768x993.jpg 768w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10-1188x1536.jpg 1188w\" data-sizes=\"(max-width: 1200px) 100vw, 1200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1552;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>The front seats are equipped with heating and ventilation as well as four-way power lumbar support and eight-way power adjustment. Furthermore, rear passengers also get their fair share with heated seats, ample legroom, and a 6.5-inch display to access the vehicle&#8217;s climate controls.<\/p>\n<p>Coming to the infotainment system, Rivian offers a massive 16-inch display perfectly compatible with all the latest features, including a 4G wifi hotspot, Android Auto and Apple Carplay. A wireless charger that can charge two smartphones is also available. And if that&#8217;s not enough,\u00a0 there are six USB Type-C charging ports and a 110V outlet. Furthermore, the infotainment system is connected to a dynamic 18-speaker Meridian sound system to create a perfect vibe for that weekend trip.<\/p>\n<p>However, one of the most innovative features is the detachable Camp Speaker with a built-in lantern. Customers can connect the speaker to their smartphone and use it as a mobile light source during camping trips.<\/p>\n<p><a href=\"https:\/\/www.emanualonline.com\/blog\/tag\/rivian\/\" target=\"_blank\" rel=\"noopener\">Rivian<\/a> aims to begin deliveries of the R1T by next month, with prices starting from $67,500.<\/p>\n<h2>Gallery<\/h2>\n<div id='gallery-2' class='gallery galleryid-33687 gallery-columns-8 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-02.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-02-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-03.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-03-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-12.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-12-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-11.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-11-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-06.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-06-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-04.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-04-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-09.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-09-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-14.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-14-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-15.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-15-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-16.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-16-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-07.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-07-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-05.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-05-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-01-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-13-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-10-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-08-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"2022 Rivian R1T\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><a href=\"https:\/\/stories.rivian.com\/r1t-interior-details\" target=\"_blank\" rel=\"noopener\"><em>Full press release<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rivian gives more insight into its highly anticipated R1T pickup truck. Back in April, Rivian released detailed specifications on the performance and capacity of its futuristic pickup truck, the all-electric R1T. The 135 kWh model features a dual-motor setup granting 754 hp of all-wheel-drive power, good enough to hit 0-60mph in just 3 seconds. It &hellip;<\/p>\n","protected":false},"author":38,"featured_media":33730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[5452,6493],"tags":[4149,4148,3988],"class_list":["post-33687","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-rivian","category-sneak-peek","tag-r1t","tag-rivian","tag-usa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rivian R1T&#039;s Highly-Functional Interior Includes a Removable Speaker<\/title>\n<meta name=\"description\" content=\"Rivian shares more insight into its much-anticipated R1T pickup, giving us a peak at the cabin featuring a couple of innovative features.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rivian R1T&#039;s Highly-Functional Interior Includes a Removable Speaker\" \/>\n<meta property=\"og:description\" content=\"Rivian gives more insight into its highly anticipated R1T pickup truck. Back in April, Rivian released detailed specifications on the performance and\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker\" \/>\n<meta property=\"og:site_name\" content=\"eManualOnline Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmanualOnline\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/arkya.das.12\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T21:22:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-24T03:14:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arkya Prava Das\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@arkya_prava\" \/>\n<meta name=\"twitter:site\" content=\"@eManualOnline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arkya Prava Das\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker\"},\"author\":{\"name\":\"Arkya Prava Das\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/person\\\/8cde6fbfbf527ff91d7ee6e0204a3441\"},\"headline\":\"Rivian R1T&#8217;s Highly-Functional Interior Includes a Removable Speaker\",\"datePublished\":\"2021-06-23T21:22:17+00:00\",\"dateModified\":\"2021-06-24T03:14:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker\"},\"wordCount\":362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/2022-Rivian-R1T-17.jpg\",\"keywords\":[\"R1T\",\"Rivian\",\"USA\"],\"articleSection\":[\"Rivian\",\"Sneak Peek\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker\",\"name\":\"Rivian R1T's Highly-Functional Interior Includes a Removable Speaker\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/2022-Rivian-R1T-17.jpg\",\"datePublished\":\"2021-06-23T21:22:17+00:00\",\"dateModified\":\"2021-06-24T03:14:25+00:00\",\"description\":\"Rivian shares more insight into its much-anticipated R1T pickup, giving us a peak at the cabin featuring a couple of innovative features.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/2022-Rivian-R1T-17.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/2022-Rivian-R1T-17.jpg\",\"width\":1200,\"height\":675,\"caption\":\"2022 Rivian R1T\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rivian R1T&#8217;s Highly-Functional Interior Includes a Removable Speaker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\",\"name\":\"eManualOnline Blog\",\"description\":\"Free Tips on Car Service, Repair and General Stuff\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\",\"name\":\"eManualOnline\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdm.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LOGO-NEW.png\",\"contentUrl\":\"https:\\\/\\\/cdm.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LOGO-NEW.png\",\"width\":512,\"height\":82,\"caption\":\"eManualOnline\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EmanualOnline\\\/\",\"https:\\\/\\\/x.com\\\/eManualOnline\",\"https:\\\/\\\/www.instagram.com\\\/emanual.online\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emanualonline\",\"https:\\\/\\\/www.pinterest.com\\\/emanualonline\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/person\\\/8cde6fbfbf527ff91d7ee6e0204a3441\",\"name\":\"Arkya Prava Das\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Bio-150x150.jpg\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Bio-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Bio-150x150.jpg\",\"caption\":\"Arkya Prava Das\"},\"description\":\"Arkya Das is a 3rd-year Electronics and Communication Engineering Student. He has been writing informative and technical articles for over two years now. He\u2019s a real car fanatic and his love for automobiles and motorsports makes him a passionate car geek.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arkya.das.12\",\"https:\\\/\\\/www.instagram.com\\\/arkya_prava_das\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/arkya-das-815b921a0\\\/\",\"https:\\\/\\\/x.com\\\/arkya_prava\"],\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/author\\\/arkya-das\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rivian R1T's Highly-Functional Interior Includes a Removable Speaker","description":"Rivian shares more insight into its much-anticipated R1T pickup, giving us a peak at the cabin featuring a couple of innovative features.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker","og_locale":"en_US","og_type":"article","og_title":"Rivian R1T's Highly-Functional Interior Includes a Removable Speaker","og_description":"Rivian gives more insight into its highly anticipated R1T pickup truck. Back in April, Rivian released detailed specifications on the performance and","og_url":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker","og_site_name":"eManualOnline Blog","article_publisher":"https:\/\/www.facebook.com\/EmanualOnline\/","article_author":"https:\/\/www.facebook.com\/arkya.das.12","article_published_time":"2021-06-23T21:22:17+00:00","article_modified_time":"2021-06-24T03:14:25+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg","type":"image\/jpeg"}],"author":"Arkya Prava Das","twitter_card":"summary_large_image","twitter_creator":"@arkya_prava","twitter_site":"@eManualOnline","twitter_misc":{"Written by":"Arkya Prava Das","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#article","isPartOf":{"@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker"},"author":{"name":"Arkya Prava Das","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/person\/8cde6fbfbf527ff91d7ee6e0204a3441"},"headline":"Rivian R1T&#8217;s Highly-Functional Interior Includes a Removable Speaker","datePublished":"2021-06-23T21:22:17+00:00","dateModified":"2021-06-24T03:14:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker"},"wordCount":362,"commentCount":0,"publisher":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage"},"thumbnailUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg","keywords":["R1T","Rivian","USA"],"articleSection":["Rivian","Sneak Peek"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker","url":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker","name":"Rivian R1T's Highly-Functional Interior Includes a Removable Speaker","isPartOf":{"@id":"https:\/\/www.emanualonline.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage"},"thumbnailUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg","datePublished":"2021-06-23T21:22:17+00:00","dateModified":"2021-06-24T03:14:25+00:00","description":"Rivian shares more insight into its much-anticipated R1T pickup, giving us a peak at the cabin featuring a couple of innovative features.","breadcrumb":{"@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#primaryimage","url":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg","contentUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg","width":1200,"height":675,"caption":"2022 Rivian R1T"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emanualonline.com\/blog\/rivian-r1ts-highly-functional-interior-includes-a-removable-speaker#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emanualonline.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Rivian R1T&#8217;s Highly-Functional Interior Includes a Removable Speaker"}]},{"@type":"WebSite","@id":"https:\/\/www.emanualonline.com\/blog\/#website","url":"https:\/\/www.emanualonline.com\/blog\/","name":"eManualOnline Blog","description":"Free Tips on Car Service, Repair and General Stuff","publisher":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emanualonline.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.emanualonline.com\/blog\/#organization","name":"eManualOnline","url":"https:\/\/www.emanualonline.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/LOGO-NEW.png","contentUrl":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/LOGO-NEW.png","width":512,"height":82,"caption":"eManualOnline"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmanualOnline\/","https:\/\/x.com\/eManualOnline","https:\/\/www.instagram.com\/emanual.online\/","https:\/\/www.linkedin.com\/company\/emanualonline","https:\/\/www.pinterest.com\/emanualonline\/"]},{"@type":"Person","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/person\/8cde6fbfbf527ff91d7ee6e0204a3441","name":"Arkya Prava Das","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2020\/08\/Bio-150x150.jpg","url":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2020\/08\/Bio-150x150.jpg","contentUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2020\/08\/Bio-150x150.jpg","caption":"Arkya Prava Das"},"description":"Arkya Das is a 3rd-year Electronics and Communication Engineering Student. He has been writing informative and technical articles for over two years now. He\u2019s a real car fanatic and his love for automobiles and motorsports makes him a passionate car geek.","sameAs":["https:\/\/www.facebook.com\/arkya.das.12","https:\/\/www.instagram.com\/arkya_prava_das\/","https:\/\/www.linkedin.com\/in\/arkya-das-815b921a0\/","https:\/\/x.com\/arkya_prava"],"url":"https:\/\/www.emanualonline.com\/blog\/author\/arkya-das"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg",1200,675,false],"thumbnail":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-150x150.jpg",150,150,true],"medium":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-768x432.jpg",618,348,true],"large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-1024x576.jpg",618,348,true],"1536x1536":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg",1200,675,false],"2048x2048":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17.jpg",1200,675,false],"tie-small":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-110x75.jpg",110,75,true],"tie-medium":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-310x165.jpg",310,165,true],"tie-large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-310x205.jpg",310,205,true],"slider":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-660x330.jpg",660,330,true],"big-slider":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/2022-Rivian-R1T-17-1050x525.jpg",1050,525,true]},"uagb_author_info":{"display_name":"Arkya Prava Das","author_link":"https:\/\/www.emanualonline.com\/blog\/author\/arkya-das"},"uagb_comment_info":0,"uagb_excerpt":"Rivian gives more insight into its highly anticipated R1T pickup truck. Back in April, Rivian released detailed specifications on the performance and capacity of its futuristic pickup truck, the all-electric R1T. The 135 kWh model features a dual-motor setup granting 754 hp of all-wheel-drive power, good enough to hit 0-60mph in just 3 seconds. It&hellip;","_links":{"self":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/33687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/comments?post=33687"}],"version-history":[{"count":4,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/33687\/revisions"}],"predecessor-version":[{"id":33732,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/33687\/revisions\/33732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/media\/33730"}],"wp:attachment":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/media?parent=33687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/categories?post=33687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/tags?post=33687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}