{"id":33579,"date":"2021-06-22T13:31:47","date_gmt":"2021-06-22T18:31:47","guid":{"rendered":"https:\/\/www.emanualonline.com\/blog\/?p=33579"},"modified":"2021-06-22T15:06:04","modified_gmt":"2021-06-22T20:06:04","slug":"forza-horizon-5-announced-as-a-next-gen-street-driving-simulator","status":"publish","type":"post","link":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator","title":{"rendered":"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator"},"content":{"rendered":"<p class=\"custom-first\">Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world.<\/p>\n<p>Forza Horizon is a household name among gamers, especially those who dig the racing simulation genre, and it looks like there\u2019s a new Forza on the horizon (sorry for the terrible pun). The fifth sequel to this popular casual street racing series defies all expectations, even surpassing 2021\u2019s high visual standards.<\/p>\n<p>Watch the lines between reality and imagery get blurred in Forza Horizon 5, as the game is reportedly going to feature some of the greatest and most realistic foliage in video game history. Developers have confirmed that graphic designers have rendered every single needle on every cactus individually, on a desert backdrop forming the perfect stage to unleash your inner street racer.<\/p>\n<p>Set in Mexico, the game takes racers around the city of Guanajuato. Dubbed as the \u201clargest and the most diverse open world ever in a <a href=\"https:\/\/www.emanualonline.com\/blog\/tag\/forza\/\" target=\"_blank\" rel=\"noopener\">Forza game<\/a>,\u201d the gameplay immerses you in a stunningly accurate recreation of the country home to the famous Baja 1000 off-road rally.<\/p>\n<p><iframe title=\"Forza Horizon 5 Official Announce Trailer\" width=\"618\" height=\"348\" data-src=\"https:\/\/www.youtube.com\/embed\/FYH9n37B7Yw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p>Based on the official trailer, players will have a variety of terrains to choose from. From a swampy and mysterious rainforest to the untamed wilderness of the desert, the game lets you enjoy Mexico&#8217;s pristine and awe-inspiring geography. If you ever dreamt of racing along the caldera of a dormant volcano, it seems that Forza Horizon 5 will answer your prayers.<\/p>\n<p>In addition to the new environment, the trailer also features some of the new cars that would be at your disposal to take on the Mexican wilderness. You can choose from an array of sporty and rugged vehicles, including, but not restricted to, the Mercedes-AMG One hypercar, Ford Bronco R, Land Rover Defender, and many more.<\/p>\n<p>Arriving on November 9th, Forza Horizon 5 would be playable on Xbox and PC. Are you ready to drive into the sandstorm that rules the Mexican lands and claim your place as the conqueror of the wilderness? We definitely are!<u><\/u><\/p>\n<p><iframe title=\"Forza Horizon 5 Official Gameplay Demo - Xbox &amp; Bethesda Games Showcase 2021\" width=\"618\" height=\"348\" data-src=\"https:\/\/www.youtube.com\/embed\/d_20X1YM28U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<h2>Gallery<\/h2>\n<div id='gallery-1' class='gallery galleryid-33579 gallery-columns-8 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"Forza Horizon 5\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-08.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-08-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"Forza Horizon 5\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-07.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-07-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"Forza Horizon 5\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-06.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-06-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-02.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-02-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"Forza Horizon 5\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-04.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-04-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-03.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-03-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-01.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-01-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail lazyload\" alt=\"Forza Horizon 5\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><a href=\"https:\/\/www.autoblog.com\/2021\/06\/19\/forza-horizon-5-gaming-roundup\/\" target=\"_blank\" rel=\"noopener\"><em>Source<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world. Forza Horizon is a household name among gamers, especially those who dig the racing simulation genre, and it looks like there\u2019s a new Forza on the horizon (sorry for the terrible pun). &hellip;<\/p>\n","protected":false},"author":58,"featured_media":33598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[10908,5326],"tags":[10207,3988],"class_list":["post-33579","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-gaming","category-news","tag-forza","tag-usa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator<\/title>\n<meta name=\"description\" content=\"Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator\" \/>\n<meta property=\"og:description\" content=\"Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world. Forza Horizon is\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator\" \/>\n<meta property=\"og:site_name\" content=\"eManualOnline Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmanualOnline\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T18:31:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-22T20:06:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anurag Sahu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@eManualOnline\" \/>\n<meta name=\"twitter:site\" content=\"@eManualOnline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anurag Sahu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator\"},\"author\":{\"name\":\"Anurag Sahu\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/person\\\/75664a7473ee77f264a4acf70d69163b\"},\"headline\":\"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator\",\"datePublished\":\"2021-06-22T18:31:47+00:00\",\"dateModified\":\"2021-06-22T20:06:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator\"},\"wordCount\":366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Forza-Horizon-5-05.jpg\",\"keywords\":[\"Forza\",\"USA\"],\"articleSection\":[\"Gaming\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator\",\"name\":\"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Forza-Horizon-5-05.jpg\",\"datePublished\":\"2021-06-22T18:31:47+00:00\",\"dateModified\":\"2021-06-22T20:06:04+00:00\",\"description\":\"Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Forza-Horizon-5-05.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Forza-Horizon-5-05.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Forza Horizon 5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\",\"name\":\"eManualOnline Blog\",\"description\":\"Free Tips on Car Service, Repair and General Stuff\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\",\"name\":\"eManualOnline\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdm.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LOGO-NEW.png\",\"contentUrl\":\"https:\\\/\\\/cdm.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LOGO-NEW.png\",\"width\":512,\"height\":82,\"caption\":\"eManualOnline\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EmanualOnline\\\/\",\"https:\\\/\\\/x.com\\\/eManualOnline\",\"https:\\\/\\\/www.instagram.com\\\/emanual.online\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emanualonline\",\"https:\\\/\\\/www.pinterest.com\\\/emanualonline\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/person\\\/75664a7473ee77f264a4acf70d69163b\",\"name\":\"Anurag Sahu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Author-Bio-Default-150x150.jpg\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Author-Bio-Default-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Author-Bio-Default-150x150.jpg\",\"caption\":\"Anurag Sahu\"},\"description\":\"Anurag Sahu is a content writing intern at EManualOnline.com and a 3rd student of Mechanical Engineering at the Indian Institute of Engineering Sciences and Technology, Shibpur. He has a knack for automobiles and driving. He aspires to work with some of his favorite car brands like Volvo or Audi as a design or production engineer. He doesn\u2019t mind being a nerd occasionally and loves to study everything under the sun about cars and automobiles. He looks forward to a much greener future where cars might look a little like the concept cars shown in spy movies. He also loves football, John Mayer, and old-school rock.\",\"sameAs\":[\"http:\\\/\\\/www.linkedin.com\\\/in\\\/anurag-sahu-96b3631b8\"],\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/author\\\/anurag-sahu\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator","description":"Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator","og_locale":"en_US","og_type":"article","og_title":"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator","og_description":"Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world. Forza Horizon is","og_url":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator","og_site_name":"eManualOnline Blog","article_publisher":"https:\/\/www.facebook.com\/EmanualOnline\/","article_published_time":"2021-06-22T18:31:47+00:00","article_modified_time":"2021-06-22T20:06:04+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg","type":"image\/jpeg"}],"author":"Anurag Sahu","twitter_card":"summary_large_image","twitter_creator":"@eManualOnline","twitter_site":"@eManualOnline","twitter_misc":{"Written by":"Anurag Sahu","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#article","isPartOf":{"@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator"},"author":{"name":"Anurag Sahu","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/person\/75664a7473ee77f264a4acf70d69163b"},"headline":"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator","datePublished":"2021-06-22T18:31:47+00:00","dateModified":"2021-06-22T20:06:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator"},"wordCount":366,"commentCount":0,"publisher":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage"},"thumbnailUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg","keywords":["Forza","USA"],"articleSection":["Gaming","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator","url":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator","name":"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator","isPartOf":{"@id":"https:\/\/www.emanualonline.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage"},"thumbnailUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg","datePublished":"2021-06-22T18:31:47+00:00","dateModified":"2021-06-22T20:06:04+00:00","description":"Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world.","breadcrumb":{"@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#primaryimage","url":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg","contentUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg","width":1200,"height":675,"caption":"Forza Horizon 5"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emanualonline.com\/blog\/forza-horizon-5-announced-as-a-next-gen-street-driving-simulator#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emanualonline.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Forza Horizon 5 Announced as a Next-Gen Street-Driving Simulator"}]},{"@type":"WebSite","@id":"https:\/\/www.emanualonline.com\/blog\/#website","url":"https:\/\/www.emanualonline.com\/blog\/","name":"eManualOnline Blog","description":"Free Tips on Car Service, Repair and General Stuff","publisher":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emanualonline.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.emanualonline.com\/blog\/#organization","name":"eManualOnline","url":"https:\/\/www.emanualonline.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/LOGO-NEW.png","contentUrl":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/LOGO-NEW.png","width":512,"height":82,"caption":"eManualOnline"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmanualOnline\/","https:\/\/x.com\/eManualOnline","https:\/\/www.instagram.com\/emanual.online\/","https:\/\/www.linkedin.com\/company\/emanualonline","https:\/\/www.pinterest.com\/emanualonline\/"]},{"@type":"Person","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/person\/75664a7473ee77f264a4acf70d69163b","name":"Anurag Sahu","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2022\/01\/Author-Bio-Default-150x150.jpg","url":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2022\/01\/Author-Bio-Default-150x150.jpg","contentUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2022\/01\/Author-Bio-Default-150x150.jpg","caption":"Anurag Sahu"},"description":"Anurag Sahu is a content writing intern at EManualOnline.com and a 3rd student of Mechanical Engineering at the Indian Institute of Engineering Sciences and Technology, Shibpur. He has a knack for automobiles and driving. He aspires to work with some of his favorite car brands like Volvo or Audi as a design or production engineer. He doesn\u2019t mind being a nerd occasionally and loves to study everything under the sun about cars and automobiles. He looks forward to a much greener future where cars might look a little like the concept cars shown in spy movies. He also loves football, John Mayer, and old-school rock.","sameAs":["http:\/\/www.linkedin.com\/in\/anurag-sahu-96b3631b8"],"url":"https:\/\/www.emanualonline.com\/blog\/author\/anurag-sahu"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg",1200,675,false],"thumbnail":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-150x150.jpg",150,150,true],"medium":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-300x169.jpg",300,169,true],"medium_large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-768x432.jpg",618,348,true],"large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-1024x576.jpg",618,348,true],"1536x1536":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg",1200,675,false],"2048x2048":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05.jpg",1200,675,false],"tie-small":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-110x75.jpg",110,75,true],"tie-medium":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-310x165.jpg",310,165,true],"tie-large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-310x205.jpg",310,205,true],"slider":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-660x330.jpg",660,330,true],"big-slider":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/06\/Forza-Horizon-5-05-1050x525.jpg",1050,525,true]},"uagb_author_info":{"display_name":"Anurag Sahu","author_link":"https:\/\/www.emanualonline.com\/blog\/author\/anurag-sahu"},"uagb_comment_info":0,"uagb_excerpt":"Microsoft just announced the all-new (and quite stunning) Forza Horizon 5 with a trailer giving us a glimpse of the new immersive world. Forza Horizon is a household name among gamers, especially those who dig the racing simulation genre, and it looks like there\u2019s a new Forza on the horizon (sorry for the terrible pun).&hellip;","_links":{"self":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/33579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/comments?post=33579"}],"version-history":[{"count":4,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/33579\/revisions"}],"predecessor-version":[{"id":33602,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/33579\/revisions\/33602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/media\/33598"}],"wp:attachment":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/media?parent=33579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/categories?post=33579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/tags?post=33579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}