{"id":18941,"date":"2021-01-26T22:57:45","date_gmt":"2021-01-27T05:57:45","guid":{"rendered":"https:\/\/www.emanualonline.com\/blog\/?p=18941"},"modified":"2023-03-24T22:01:05","modified_gmt":"2023-03-25T03:01:05","slug":"city-transformer-ct-1-is-the-folding-electric-car-of-the-future","status":"publish","type":"post","link":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future","title":{"rendered":"City Transformer CT-1 is the Folding Electric Car of the Future"},"content":{"rendered":"<p style=\"color: #ef8b09; font-size: large;\">City Transformer, an Israeli startup, announced an urban EV that can shrink to fit into tighter parking spaces.<\/p>\n<p>Traffic jams and lack of parking areas are the two most common problems people face in <a href=\"https:\/\/www.emanualonline.com\/blog\/tag\/urban-mobility\/\" target=\"_blank\" rel=\"noopener noreferrer\">urban driving<\/a> scenarios. Several ideas have been put forward to solve these issues, including taxing drivers from other towns, carpooling, and even flying cars\u2014however, no need to mention that nobody really came up with a satisfying solution yet.<\/p>\n<p>Staying true to the saying, \u201cNecessity is the mother of invention,\u201d the Israeli-based startup City Transformer has come up with a very creative solution. Namely, the company has developed a compact <a href=\"https:\/\/www.emanualonline.com\/blog\/tag\/ev\/\" target=\"_blank\" rel=\"noopener noreferrer\">EV<\/a> that can shrink to fit into congested parking spots.<\/p>\n<div class=\"one_half\">\n<p><a href=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18969 lazyload\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-2.jpg\" alt=\"City Transformer CT-1 folding electric city vehicle\" width=\"550\" height=\"560\" data-srcset=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-2.jpg 550w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-2-295x300.jpg 295w\" data-sizes=\"(max-width: 550px) 100vw, 550px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/560;\" \/><\/a><\/p>\n<\/div><div class=\"one_half last\">\n<p><a href=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18968 lazyload\" data-src=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-1.jpg\" alt=\"City Transformer CT-1 folding electric city vehicle\" width=\"550\" height=\"560\" data-srcset=\"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-1.jpg 550w, https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-1-295x300.jpg 295w\" data-sizes=\"(max-width: 550px) 100vw, 550px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/560;\" \/><\/a><\/p>\n<\/div><div class=\"clear\"><\/div>\n<p>Named the CT-1, this four-wheel EV is initially 292.5\u2019 long and 56.7\u2019 wide. However, it can retract its wheels to just 1m wide, allowing it to pass through narrow lanes and ease parking. The company claims that four City Transformers can fit in a standard parking spot.<\/p>\n<p>Unlike the track, the passenger area does not change shape while folding. Concretely, it can seat four passengers \u2013 two adults (including the driver) in the front and two children in the back.<\/p>\n<p>Moreover, it\u00a0can run up to 75-110 miles on a single charge and reach a top speed of 55 mph in wide mode and about 28 mph when narrow.<\/p>\n<p>Times Magazine even listed the CT-1 as one of the 100 Best Inventions of 2020.<\/p>\n<p>City Transformer has announced plans to go public on the Tel Aviv Stock Exchange (TASE) at the beginning of March. Its current valuation is estimated between $137 million to $183 million. The\u00a0startup hopes to acquire a regulatory certificate for the CT-1 under the Quadricycle category to enter the European market.<\/p>\n<p>Once done, Germany\u2019s Roding Automobile will be responsible for manufacturing the CT-1, while City Transformer aims to start selling the vehicle by 2022. However, mass production will only begin in 2023, possibly in China.<\/p>\n<p>We&#8217;ll keep an eye on this one for you. Stay tuned!<\/p>\n<p><a href=\"https:\/\/en.globes.co.il\/en\/article-folding-car-co-city-transformer-plans-tase-ipo-1001358225\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Source<\/em><\/a><\/p>\n<p class=\"has-background has-text-align-center has-very-light-gray-background-color\"><strong>Download 2.5M+ <a href=\"https:\/\/www.emanualonline.com\/cars.htm\" target=\"_blank\" rel=\"noopener\">car repair manuals<\/a> here!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>City Transformer, an Israeli startup, announced an urban EV that can shrink to fit into tighter parking spaces. Traffic jams and lack of parking areas are the two most common problems people face in urban driving scenarios. Several ideas have been put forward to solve these issues, including taxing drivers from other towns, carpooling, and &hellip;<\/p>\n","protected":false},"author":53,"featured_media":18967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[10518,10253],"tags":[10840,167,10257],"class_list":["post-18941","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-bev","category-urban-mobility","tag-city-transformer","tag-ev","tag-urban-mobility"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>City Transformer CT-1 is the Folding Electric Car of the Future<\/title>\n<meta name=\"description\" content=\"City Transformer, an Israeli startup, announced an urban EV that sits four passengers and can shrink to fit into tighter parking spaces.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"City Transformer CT-1 is the Folding Electric Car of the Future\" \/>\n<meta property=\"og:description\" content=\"City Transformer, an Israeli startup, announced an urban EV that can shrink to fit into tighter parking spaces. Traffic jams and lack of parking areas are\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future\" \/>\n<meta property=\"og:site_name\" content=\"eManualOnline Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EmanualOnline\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T05:57:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-25T03:01:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fakhruddin Modi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ModiFakhruddin\" \/>\n<meta name=\"twitter:site\" content=\"@eManualOnline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fakhruddin Modi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future\"},\"author\":{\"name\":\"Fakhruddin Modi\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/person\\\/f2a00776d55c1b709ac50bc6454bbb70\"},\"headline\":\"City Transformer CT-1 is the Folding Electric Car of the Future\",\"datePublished\":\"2021-01-27T05:57:45+00:00\",\"dateModified\":\"2023-03-25T03:01:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png\",\"keywords\":[\"City Transformer\",\"EV\",\"Urban Mobility\"],\"articleSection\":[\"BEV\",\"Urban Mobility\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future\",\"name\":\"City Transformer CT-1 is the Folding Electric Car of the Future\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png\",\"datePublished\":\"2021-01-27T05:57:45+00:00\",\"dateModified\":\"2023-03-25T03:01:05+00:00\",\"description\":\"City Transformer, an Israeli startup, announced an urban EV that sits four passengers and can shrink to fit into tighter parking spaces.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png\",\"contentUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png\",\"width\":1200,\"height\":600,\"caption\":\"City Transformer CT-1 folding electric city vehicle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"City Transformer CT-1 is the Folding Electric Car of the Future\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\",\"name\":\"eManualOnline Blog\",\"description\":\"Free Tips on Car Service, Repair and General Stuff\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#organization\",\"name\":\"eManualOnline\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdm.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LOGO-NEW.png\",\"contentUrl\":\"https:\\\/\\\/cdm.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/LOGO-NEW.png\",\"width\":512,\"height\":82,\"caption\":\"eManualOnline\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EmanualOnline\\\/\",\"https:\\\/\\\/x.com\\\/eManualOnline\",\"https:\\\/\\\/www.instagram.com\\\/emanual.online\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/emanualonline\",\"https:\\\/\\\/www.pinterest.com\\\/emanualonline\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/#\\\/schema\\\/person\\\/f2a00776d55c1b709ac50bc6454bbb70\",\"name\":\"Fakhruddin Modi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Fakhruddin-Modi-Copy-150x150.jpg\",\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Fakhruddin-Modi-Copy-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Fakhruddin-Modi-Copy-150x150.jpg\",\"caption\":\"Fakhruddin Modi\"},\"description\":\"Fakhruddin Modi is a college student currently in the second year of his graduation. Being a digital marketing trainee, he is skilled in Blog writing as well as social media marketing and no-code website development. He likes to create digital art in Photoshop and Canva, just for fun. His hobbies include singing, bike riding, painting, and photography. He also loves to play cricket, travel to distant locations, and meet new people.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/fakhri.modi87\\\/\",\"https:\\\/\\\/x.com\\\/ModiFakhruddin\"],\"url\":\"https:\\\/\\\/www.emanualonline.com\\\/blog\\\/author\\\/fakhruddin-modi\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"City Transformer CT-1 is the Folding Electric Car of the Future","description":"City Transformer, an Israeli startup, announced an urban EV that sits four passengers and can shrink to fit into tighter parking spaces.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future","og_locale":"en_US","og_type":"article","og_title":"City Transformer CT-1 is the Folding Electric Car of the Future","og_description":"City Transformer, an Israeli startup, announced an urban EV that can shrink to fit into tighter parking spaces. Traffic jams and lack of parking areas are","og_url":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future","og_site_name":"eManualOnline Blog","article_publisher":"https:\/\/www.facebook.com\/EmanualOnline\/","article_published_time":"2021-01-27T05:57:45+00:00","article_modified_time":"2023-03-25T03:01:05+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png","type":"image\/png"}],"author":"Fakhruddin Modi","twitter_card":"summary_large_image","twitter_creator":"@ModiFakhruddin","twitter_site":"@eManualOnline","twitter_misc":{"Written by":"Fakhruddin Modi","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#article","isPartOf":{"@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future"},"author":{"name":"Fakhruddin Modi","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/person\/f2a00776d55c1b709ac50bc6454bbb70"},"headline":"City Transformer CT-1 is the Folding Electric Car of the Future","datePublished":"2021-01-27T05:57:45+00:00","dateModified":"2023-03-25T03:01:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage"},"thumbnailUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png","keywords":["City Transformer","EV","Urban Mobility"],"articleSection":["BEV","Urban Mobility"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future","url":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future","name":"City Transformer CT-1 is the Folding Electric Car of the Future","isPartOf":{"@id":"https:\/\/www.emanualonline.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage"},"thumbnailUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png","datePublished":"2021-01-27T05:57:45+00:00","dateModified":"2023-03-25T03:01:05+00:00","description":"City Transformer, an Israeli startup, announced an urban EV that sits four passengers and can shrink to fit into tighter parking spaces.","breadcrumb":{"@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#primaryimage","url":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png","contentUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png","width":1200,"height":600,"caption":"City Transformer CT-1 folding electric city vehicle"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emanualonline.com\/blog\/city-transformer-ct-1-is-the-folding-electric-car-of-the-future#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emanualonline.com\/blog\/"},{"@type":"ListItem","position":2,"name":"City Transformer CT-1 is the Folding Electric Car of the Future"}]},{"@type":"WebSite","@id":"https:\/\/www.emanualonline.com\/blog\/#website","url":"https:\/\/www.emanualonline.com\/blog\/","name":"eManualOnline Blog","description":"Free Tips on Car Service, Repair and General Stuff","publisher":{"@id":"https:\/\/www.emanualonline.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emanualonline.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.emanualonline.com\/blog\/#organization","name":"eManualOnline","url":"https:\/\/www.emanualonline.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/LOGO-NEW.png","contentUrl":"https:\/\/cdm.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/LOGO-NEW.png","width":512,"height":82,"caption":"eManualOnline"},"image":{"@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EmanualOnline\/","https:\/\/x.com\/eManualOnline","https:\/\/www.instagram.com\/emanual.online\/","https:\/\/www.linkedin.com\/company\/emanualonline","https:\/\/www.pinterest.com\/emanualonline\/"]},{"@type":"Person","@id":"https:\/\/www.emanualonline.com\/blog\/#\/schema\/person\/f2a00776d55c1b709ac50bc6454bbb70","name":"Fakhruddin Modi","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/Fakhruddin-Modi-Copy-150x150.jpg","url":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/Fakhruddin-Modi-Copy-150x150.jpg","contentUrl":"https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/04\/Fakhruddin-Modi-Copy-150x150.jpg","caption":"Fakhruddin Modi"},"description":"Fakhruddin Modi is a college student currently in the second year of his graduation. Being a digital marketing trainee, he is skilled in Blog writing as well as social media marketing and no-code website development. He likes to create digital art in Photoshop and Canva, just for fun. His hobbies include singing, bike riding, painting, and photography. He also loves to play cricket, travel to distant locations, and meet new people.","sameAs":["https:\/\/www.instagram.com\/fakhri.modi87\/","https:\/\/x.com\/ModiFakhruddin"],"url":"https:\/\/www.emanualonline.com\/blog\/author\/fakhruddin-modi"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png",1200,600,false],"thumbnail":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-150x150.png",150,150,true],"medium":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-300x150.png",300,150,true],"medium_large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-768x384.png",618,309,true],"large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-1024x512.png",618,309,true],"1536x1536":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png",1200,600,false],"2048x2048":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured.png",1200,600,false],"tie-small":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-110x75.png",110,75,true],"tie-medium":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-310x165.png",310,165,true],"tie-large":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-310x205.png",310,205,true],"slider":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-660x330.png",660,330,true],"big-slider":["https:\/\/www.emanualonline.com\/blog\/wp-content\/uploads\/2021\/01\/City-Transformer-CT-1-folding-electric-city-vehicle-featured-1050x525.png",1050,525,true]},"uagb_author_info":{"display_name":"Fakhruddin Modi","author_link":"https:\/\/www.emanualonline.com\/blog\/author\/fakhruddin-modi"},"uagb_comment_info":0,"uagb_excerpt":"City Transformer, an Israeli startup, announced an urban EV that can shrink to fit into tighter parking spaces. Traffic jams and lack of parking areas are the two most common problems people face in urban driving scenarios. Several ideas have been put forward to solve these issues, including taxing drivers from other towns, carpooling, and&hellip;","_links":{"self":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/18941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/comments?post=18941"}],"version-history":[{"count":7,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/18941\/revisions"}],"predecessor-version":[{"id":55526,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/posts\/18941\/revisions\/55526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/media\/18967"}],"wp:attachment":[{"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/media?parent=18941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/categories?post=18941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emanualonline.com\/blog\/wp-json\/wp\/v2\/tags?post=18941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}